{"id":54511,"date":"2023-12-31T15:29:08","date_gmt":"2023-12-31T15:29:08","guid":{"rendered":"https:\/\/myedme.com\/login\/?page_id=54511"},"modified":"2023-12-31T15:29:09","modified_gmt":"2023-12-31T15:29:09","slug":"tutoring-interest","status":"publish","type":"page","link":"https:\/\/myedme.com\/login\/tutoring-interest\/","title":{"rendered":"Tutoring Interest"},"content":{"rendered":"<div class=\"wpforms-container wpforms-container-full wpforms-block wpforms-block-e32407e0-0fa7-40a4-b8d9-46f7380a19b7\" id=\"wpforms-54507\"><form id=\"wpforms-form-54507\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"54507\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/login\/wp-json\/wp\/v2\/pages\/54511\" data-token=\"295a989d68c6abd202ab0c1c39ba46e9\" data-token-time=\"1778700670\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-54507-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"0\"><label class=\"wpforms-field-label\" for=\"wpforms-54507-field_0\">Student Name <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-54507-field_0\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][0]\" required><\/div><div id=\"wpforms-54507-field_8-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-inline\" data-field-id=\"8\"><label class=\"wpforms-field-label\">Subjects for Tutoring (check all that apply) <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-54507-field_8\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-54507-field_8_1\" name=\"wpforms[fields][8][]\" value=\"Reading\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-54507-field_8_1\">Reading<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-54507-field_8_2\" name=\"wpforms[fields][8][]\" value=\"Math\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-54507-field_8_2\">Math<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-54507-field_8_3\" name=\"wpforms[fields][8][]\" value=\"Science\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-54507-field_8_3\">Science<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-54507-field_8_4\" name=\"wpforms[fields][8][]\" value=\"Social Studies\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-54507-field_8_4\">Social Studies<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"checkbox\" id=\"wpforms-54507-field_8_5\" name=\"wpforms[fields][8][]\" value=\"Language\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-54507-field_8_5\">Language<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"checkbox\" id=\"wpforms-54507-field_8_6\" name=\"wpforms[fields][8][]\" value=\"Electives\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-54507-field_8_6\">Electives<\/label><\/li><\/ul><\/div><div id=\"wpforms-54507-field_6-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-inline\" data-field-id=\"6\"><label class=\"wpforms-field-label\">Best Days to Meet (check all that apply) <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-54507-field_6\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-54507-field_6_1\" name=\"wpforms[fields][6][]\" value=\"Monday\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-54507-field_6_1\">Monday<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-54507-field_6_2\" name=\"wpforms[fields][6][]\" value=\"Tuesday\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-54507-field_6_2\">Tuesday<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-54507-field_6_3\" name=\"wpforms[fields][6][]\" value=\"Wednesday\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-54507-field_6_3\">Wednesday<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-54507-field_6_4\" name=\"wpforms[fields][6][]\" value=\"Thursday\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-54507-field_6_4\">Thursday<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"checkbox\" id=\"wpforms-54507-field_6_5\" name=\"wpforms[fields][6][]\" value=\"Friday\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-54507-field_6_5\">Friday<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"checkbox\" id=\"wpforms-54507-field_6_6\" name=\"wpforms[fields][6][]\" value=\"Saturday\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-54507-field_6_6\">Saturday<\/label><\/li><li class=\"choice-7 depth-1\"><input type=\"checkbox\" id=\"wpforms-54507-field_6_7\" name=\"wpforms[fields][6][]\" value=\"Sunday\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-54507-field_6_7\">Sunday<\/label><\/li><\/ul><\/div><div id=\"wpforms-54507-field_7-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-inline\" data-field-id=\"7\"><label class=\"wpforms-field-label\">Best Times to Meet (check all that apply) <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-54507-field_7\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-54507-field_7_1\" name=\"wpforms[fields][7][]\" value=\"Morning\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-54507-field_7_1\">Morning<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-54507-field_7_2\" name=\"wpforms[fields][7][]\" value=\"Mid-morning\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-54507-field_7_2\">Mid-morning<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-54507-field_7_3\" name=\"wpforms[fields][7][]\" value=\"Afternoon\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-54507-field_7_3\">Afternoon<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-54507-field_7_4\" name=\"wpforms[fields][7][]\" value=\"Mid-afternoon\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-54507-field_7_4\">Mid-afternoon<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"checkbox\" id=\"wpforms-54507-field_7_5\" name=\"wpforms[fields][7][]\" value=\"Evening\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-54507-field_7_5\">Evening<\/label><\/li><\/ul><\/div><div id=\"wpforms-54507-field_9-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-inline\" data-field-id=\"9\"><label class=\"wpforms-field-label\">Tutoring Type Preference (check all that apply) <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-54507-field_9\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-54507-field_9_1\" name=\"wpforms[fields][9][]\" value=\"in-home\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-54507-field_9_1\">in-home<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-54507-field_9_2\" name=\"wpforms[fields][9][]\" value=\"at a location\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-54507-field_9_2\">at a location<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-54507-field_9_3\" name=\"wpforms[fields][9][]\" value=\"at edMe\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-54507-field_9_3\">at edMe<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-54507-field_9_4\" name=\"wpforms[fields][9][]\" value=\"online\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-54507-field_9_4\">online<\/label><\/li><\/ul><\/div><div id=\"wpforms-54507-field_3-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"3\"><label class=\"wpforms-field-label\">Parent\/Gaurdian Name <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-54507-field_3\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][3][first]\" required><label for=\"wpforms-54507-field_3\" class=\"wpforms-field-sublabel after\">First<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-54507-field_3-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][3][last]\" required><label for=\"wpforms-54507-field_3-last\" class=\"wpforms-field-sublabel after\">Last<\/label><\/div><\/div><\/div><div id=\"wpforms-54507-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-54507-field_1\">Contact Email <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-54507-field_1\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][1]\" spellcheck=\"false\" required><\/div><div id=\"wpforms-54507-field_11-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"11\"><label class=\"wpforms-field-label\" for=\"wpforms-54507-field_11\">Contact Phone (optional)<\/label><input type=\"text\" id=\"wpforms-54507-field_11\" class=\"wpforms-field-medium\" name=\"wpforms[fields][11]\" ><\/div><div id=\"wpforms-54507-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-54507-field_2\">Comment or Message<\/label><textarea id=\"wpforms-54507-field_2\" class=\"wpforms-field-medium\" name=\"wpforms[fields][2]\" ><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-recaptcha-container wpforms-is-recaptcha wpforms-is-recaptcha-type-v2\" ><div class=\"g-recaptcha\" data-sitekey=\"6Lcjr0EpAAAAAGoWyh5E-6MWMvZF0UrYGanfQkxG\"><\/div><input type=\"text\" name=\"g-recaptcha-hidden\" class=\"wpforms-recaptcha-hidden\" style=\"position:absolute!important;clip:rect(0,0,0,0)!important;height:1px!important;width:1px!important;border:0!important;overflow:hidden!important;padding:0!important;margin:0!important;\" data-rule-recaptcha=\"1\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"54507\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/myedme.com\/login\/wp-json\/wp\/v2\/pages\/54511\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-54507\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Submit<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/myedme.com\/login\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container -->","protected":false},"excerpt":{"rendered":"","protected":false},"author":71,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"nf_dc_page":"","footnotes":""},"class_list":["post-54511","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/myedme.com\/login\/wp-json\/wp\/v2\/pages\/54511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/myedme.com\/login\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/myedme.com\/login\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/myedme.com\/login\/wp-json\/wp\/v2\/users\/71"}],"replies":[{"embeddable":true,"href":"https:\/\/myedme.com\/login\/wp-json\/wp\/v2\/comments?post=54511"}],"version-history":[{"count":1,"href":"https:\/\/myedme.com\/login\/wp-json\/wp\/v2\/pages\/54511\/revisions"}],"predecessor-version":[{"id":54512,"href":"https:\/\/myedme.com\/login\/wp-json\/wp\/v2\/pages\/54511\/revisions\/54512"}],"wp:attachment":[{"href":"https:\/\/myedme.com\/login\/wp-json\/wp\/v2\/media?parent=54511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}